{"id":41640,"date":"2024-07-24T09:40:45","date_gmt":"2024-07-24T07:40:45","guid":{"rendered":"https:\/\/www.linseis.com\/messgeraete\/dispositifs-supplementaires-et-soutien\/ega-qms\/"},"modified":"2025-07-30T13:54:12","modified_gmt":"2025-07-30T11:54:12","slug":"l40-ega-qms","status":"publish","type":"messgeraete","link":"https:\/\/www.linseis.com\/fr\/produits\/dispositifs-complementaires-et-accessoires\/l40-ega-qms\/","title":{"rendered":"L40 EGA QMS"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"41640\" class=\"elementor elementor-41640 elementor-19482\" data-elementor-post-type=\"messgeraete\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a2ed6e0 e-flex e-con-boxed e-con e-parent\" data-id=\"a2ed6e0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5cf88cf e-con-full e-flex e-con e-child\" data-id=\"5cf88cf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a3fee26 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"a3fee26\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67f10a9 elementor-align-right elementor-widget__width-auto btn-fancy elementor-invisible elementor-widget elementor-widget-button\" data-id=\"67f10a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#uniquefeatures\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Caract\u00e9ristiques uniques<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd631ea elementor-align-right elementor-widget__width-auto btn-fancy elementor-invisible elementor-widget elementor-widget-button\" data-id=\"bd631ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#specifications\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Sp\u00e9cifications<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ed112a elementor-align-right elementor-widget__width-auto btn-fancy elementor-invisible elementor-widget elementor-widget-button\" data-id=\"8ed112a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#applications\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Votre industrie<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61f758a elementor-align-right elementor-widget__width-auto btn-fancy elementor-invisible elementor-widget elementor-widget-button\" data-id=\"61f758a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#downloads\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">T\u00e9l\u00e9chargements<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f98d1e elementor-align-right elementor-widget__width-auto btn-fancy elementor-invisible elementor-widget elementor-widget-button\" data-id=\"1f98d1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.linseis.com\/fr\/contact-demandes-de-devis\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Demander un devis<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ba0a7a0 e-flex e-con-boxed e-con e-parent\" data-id=\"ba0a7a0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5423f91 e-con-full e-flex e-con e-child\" data-id=\"5423f91\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fee8130 elementor-widget elementor-widget-menu-anchor\" data-id=\"fee8130\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"description\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31a1020 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"31a1020\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:250}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L40 EGA QMS -  Description<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa4565b elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"fa4565b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">En bref<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0695aaa e-con-full e-flex e-con e-child\" data-id=\"0695aaa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ea1a15e e-flex e-con-boxed e-con e-parent\" data-id=\"ea1a15e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4a7f781 e-con-full e-flex e-con e-child\" data-id=\"4a7f781\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-151daf6 elementor-widget elementor-widget-text-editor\" data-id=\"151daf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"spb_content_element col-sm-6 spb_text_column\">\n<h3>Qu\u2019est-ce que la spectrom\u00e9trie de masse (MS) ?<\/h3>\nLa<b>\u00a0spectrom\u00e9trie de masse (MS)<\/b>\u00a0est une technique analytique permettant de mesurer la masse d\u2019atomes ou de mol\u00e9cules.\n\nDans l\u2019<a href=\"https:\/\/www.linseis.com\/fr\/produits\/analyse-thermique\/\">analyse thermique<\/a>, les \u00e9chantillons sont g\u00e9n\u00e9ralement donn\u00e9s sous forme de compos\u00e9s gazeux, par exemple par \u00e9vaporation d\u2019un \u00e9chantillon chauff\u00e9. Les spectres r\u00e9sultants sont utilis\u00e9s pour d\u00e9terminer la signature \u00e9l\u00e9mentaire ou isotopique d\u2019un \u00e9chantillon, les masses des particules et des mol\u00e9cules et pour \u00e9lucider les structures chimiques des mol\u00e9cules.\n<h3>Comment fonctionne la spectrom\u00e9trie de masse ?<\/h3>\nLa spectrom\u00e9trie de masse fonctionne en ionisant les compos\u00e9s chimiques pour cr\u00e9er des mol\u00e9cules ou des fragments de mol\u00e9cules charg\u00e9s et en mesurant leur rapport masse\/charge en pla\u00e7ant les mol\u00e9cules charg\u00e9es dans un champ magn\u00e9tique (quadrip\u00f4le) et en surveillant leur interaction.\n<h3>Qu\u2019est-ce que le QMS (spectrom\u00e8tre de masse quadripolaire) ?<\/h3>\nLe QMS \u2013 couplage de spectrom\u00e8tre de masse quadripolaire est un spectrom\u00e8tre de masse de pointe avec un syst\u00e8me d\u2019entr\u00e9e chauff\u00e9. Le QMS est utilis\u00e9 pour l\u2019analyse de la d\u00e9composition volatile. Tous les <a href=\"https:\/\/www.linseis.com\/fr\/\">appareils Linseis<\/a> offrent une solution logicielle int\u00e9gr\u00e9e qui permet d\u2019\u00e9valuer simultan\u00e9ment l\u2019analyse thermique et la technique EGA.\n<h3>Quels sont les avantages du couplage d\u2019une thermobalance Linseis avec un spectrom\u00e8tre de masse ?<\/h3>\nLe couplage de la thermobalance Linseis avec un spectrom\u00e8tre de masse permet d\u2019obtenir un r\u00e9sultat tr\u00e8s fiable.\u00a0<a href=\"https:\/\/www.linseis.com\/fr\/produits\/dispositifs-complementaires-et-accessoires\/ega-gas-analysis\/\" data-auto-event-observed=\"true\"><b>EGA<\/b><\/a>\u00a0(analyse des gaz d\u2019\u00e9mission).\n\nCela peut fournir des informations tr\u00e8s int\u00e9ressantes pour la caract\u00e9risation des mat\u00e9riaux lors du d\u00e9veloppement de nouvelles c\u00e9ramiques, de produits pharmaceutiques ou de polym\u00e8res et de m\u00e9taux. Il est \u00e9galement possible d\u2019effectuer des \u00e9tudes sur l\u2019impact environnemental des produits qui d\u00e9gagent des gaz, par exemple lors de la gestion des d\u00e9chets\/de l\u2019incin\u00e9ration ou dans les ateliers de peinture automobile.\n<h3><strong>Caract\u00e9ristiques du spectrom\u00e8tre de masse<\/strong><\/h3>\n<ul>\n \t<li>Balance de recherche Top-Shell (diff\u00e9rents mod\u00e8les) ; TG ou\u00a0<a href=\"https:\/\/www.linseis.com\/fr\/produits\/analyse-thermique\/sta-simultaneous-thermal-analysis\/\" data-auto-event-observed=\"true\"><b>STA<\/b><\/a>\u00a0(TG+DTA\/DSC)<\/li>\n \t<li>TG\/DSC ou TG\/DTA simultan\u00e9s \u00e0 haute r\u00e9solution (0,1\/0,5\/1 \u00b5g)<\/li>\n \t<li>Poids d\u2019\u00e9chantillon \u00e9lev\u00e9 max. 25 g<\/li>\n \t<li>Spectrom\u00e8tre de masse Pfeiffer\/MKS (0 \u2013 100 AMU, 0 \u2013 200 AMU,<\/li>\n \t<li>0 \u2013 300 AMU)<\/li>\n \t<li>Capillaires en quartz facilement rempla\u00e7ables<\/li>\n \t<li>Trois zones de chauffage s\u00e9par\u00e9es : Capillaire\/tube de protection TG\/t\u00eate d\u2019adaptation du spectrom\u00e8tre de masse<\/li>\n \t<li>Possibilit\u00e9 de faibles d\u00e9bits de gaz de purge<\/li>\n \t<li>Nez \u00ab\u00a0renifleur\u00a0\u00bb d\u2019Al<sub>2<\/sub>O<sub>3<\/sub>\u00a0sp\u00e9cialement con\u00e7u pour extraire les d\u00e9gagements gazeux<\/li>\n \t<li>Affichage commun des signaux TG et MS<\/li>\n \t<li>Syst\u00e8me \u00e9tanche au vide<\/li>\n \t<li>G\u00e9om\u00e9trie de la chambre d\u2019\u00e9chantillon sp\u00e9cialement con\u00e7ue<\/li>\n<\/ul>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fa47f69 e-flex e-con-boxed e-con e-parent\" data-id=\"fa47f69\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ce41174 e-con-full e-flex e-con e-child\" data-id=\"ce41174\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3548ac7 elementor-widget elementor-widget-menu-anchor\" data-id=\"3548ac7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"uniquefeatures\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff61679 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ff61679\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:250}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Spectrom\u00e8tre de masse EGA - QMS - Caract\u00e9ristiques uniques<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-231a2d1 e-con-full e-flex e-con e-child\" data-id=\"231a2d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-54e9337 e-flex e-con-boxed e-con e-parent\" data-id=\"54e9337\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c08f4f elementor-invisible elementor-widget elementor-widget-hotspot\" data-id=\"5c08f4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hotspot&quot;:[{&quot;_id&quot;:&quot;1d59cc6&quot;,&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;&lt;strong&gt;Haute sensibilit\\u00e9 de d\\u00e9tection&lt;\\\/strong&gt;: &lt;br \\\/&gt;Spectrom\\u00e8tre chauff\\u00e9 pour l&#039;analyse &lt;br \\\/&gt;des gaz de d\\u00e9composition lib\\u00e9r\\u00e9s.&lt;\\\/p&gt;\\n&quot;,&quot;hotspot_horizontal&quot;:&quot;right&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:48,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:13,&quot;sizes&quot;:[]},&quot;hotspot_icon&quot;:{&quot;value&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.linseis.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/linseis-hotspot.svg&quot;,&quot;id&quot;:1993},&quot;library&quot;:&quot;svg&quot;},&quot;hotspot_icon_spacing&quot;:null,&quot;hotspot_custom_size&quot;:&quot;&quot;,&quot;hotspot_width&quot;:null,&quot;hotspot_height&quot;:null,&quot;hotspot_tooltip_position&quot;:&quot;yes&quot;,&quot;hotspot_position&quot;:&quot;left&quot;,&quot;hotspot_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;index&quot;:0,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position_tablet&quot;:&quot;&quot;,&quot;hotspot_position_mobile&quot;:&quot;&quot;,&quot;hotspot_icon_position&quot;:null,&quot;hotspot_offset_x_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_x_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_text_wrap&quot;:&quot;&quot;},{&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;&lt;b&gt;Compatibilit\\u00e9 :&lt;\\\/b&gt;&lt;\\\/p&gt;\\n&lt;p&gt;Couplage facile avec les thermobalances (TG),&lt;\\\/p&gt;\\n&lt;p&gt;Analyse thermique simultan\\u00e9e (STA) et autres appareils thermoanalytiques.&lt;\\\/p&gt;\\n&lt;p&gt;G\\u00e9om\\u00e9trie flexible pour une adaptation optimale \\u00e0 l&#039;espace de laboratoire disponible.&lt;\\\/p&gt;\\n&quot;,&quot;hotspot_horizontal&quot;:&quot;right&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:34,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:39,&quot;sizes&quot;:[]},&quot;hotspot_icon&quot;:{&quot;value&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.linseis.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/linseis-hotspot.svg&quot;,&quot;id&quot;:1993},&quot;library&quot;:&quot;svg&quot;},&quot;hotspot_icon_spacing&quot;:null,&quot;hotspot_custom_size&quot;:&quot;&quot;,&quot;hotspot_width&quot;:null,&quot;hotspot_height&quot;:null,&quot;hotspot_tooltip_position&quot;:&quot;yes&quot;,&quot;hotspot_position&quot;:&quot;right&quot;,&quot;hotspot_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;_id&quot;:&quot;d909940&quot;,&quot;index&quot;:1,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position_tablet&quot;:&quot;&quot;,&quot;hotspot_position_mobile&quot;:&quot;&quot;,&quot;hotspot_icon_position&quot;:null,&quot;hotspot_offset_x_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_x_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_text_wrap&quot;:&quot;&quot;},{&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;&lt;strong&gt;Trois zones de chauffage s\\u00e9par\\u00e9es :&lt;\\\/strong&gt; &lt;br \\\/&gt;Assurer un minimum d&#039;effets de dilution &lt;br \\\/&gt;et &lt;br \\\/&gt;des r\\u00e9sultats pr\\u00e9cis.&lt;\\\/p&gt;\\n&quot;,&quot;hotspot_horizontal&quot;:&quot;right&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:51,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:78,&quot;sizes&quot;:[]},&quot;hotspot_icon&quot;:{&quot;value&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.linseis.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/linseis-hotspot.svg&quot;,&quot;id&quot;:1993},&quot;library&quot;:&quot;svg&quot;},&quot;hotspot_icon_spacing&quot;:null,&quot;hotspot_custom_size&quot;:&quot;&quot;,&quot;hotspot_width&quot;:null,&quot;hotspot_height&quot;:null,&quot;hotspot_tooltip_position&quot;:&quot;yes&quot;,&quot;hotspot_position&quot;:&quot;right&quot;,&quot;hotspot_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;_id&quot;:&quot;a507cce&quot;,&quot;index&quot;:2,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position_tablet&quot;:&quot;&quot;,&quot;hotspot_position_mobile&quot;:&quot;&quot;,&quot;hotspot_icon_position&quot;:null,&quot;hotspot_offset_x_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_x_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_text_wrap&quot;:&quot;&quot;},{&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;&lt;b&gt;Applications multiples :&lt;\\\/b&gt;&lt;\\\/p&gt;\\n&lt;p&gt;Spectroscopie de masse en ligne \\u00e0 haute r\\u00e9solution en phase gazeuse jusqu&#039;\\u00e0 300 AMU&lt;\\\/p&gt;\\n&quot;,&quot;hotspot_horizontal&quot;:&quot;right&quot;,&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:39,&quot;sizes&quot;:[]},&quot;hotspot_icon&quot;:{&quot;value&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.linseis.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/linseis-hotspot.svg&quot;,&quot;id&quot;:1993},&quot;library&quot;:&quot;svg&quot;},&quot;hotspot_icon_spacing&quot;:null,&quot;hotspot_custom_size&quot;:&quot;yes&quot;,&quot;hotspot_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;hotspot_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_position&quot;:&quot;yes&quot;,&quot;hotspot_position&quot;:&quot;left&quot;,&quot;hotspot_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;_id&quot;:&quot;24ed251&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:65,&quot;sizes&quot;:[]},&quot;index&quot;:3,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position_tablet&quot;:&quot;&quot;,&quot;hotspot_position_mobile&quot;:&quot;&quot;,&quot;hotspot_icon_position&quot;:null,&quot;hotspot_offset_x_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_x_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_text_wrap&quot;:&quot;&quot;},{&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;&lt;strong&gt;Conception robuste&lt;\\\/strong&gt;: &lt;br \\\/&gt;Syst\\u00e8me \\u00e9tanche au vide &lt;br \\\/&gt;pour des mesures fiables et &lt;br \\\/&gt;r\\u00e9p\\u00e9tables.&lt;\\\/p&gt;\\n&quot;,&quot;hotspot_horizontal&quot;:&quot;right&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:25,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:49,&quot;sizes&quot;:[]},&quot;hotspot_icon&quot;:{&quot;value&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.linseis.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/linseis-hotspot.svg&quot;,&quot;id&quot;:1993},&quot;library&quot;:&quot;svg&quot;},&quot;hotspot_icon_spacing&quot;:null,&quot;hotspot_custom_size&quot;:&quot;&quot;,&quot;hotspot_width&quot;:null,&quot;hotspot_height&quot;:null,&quot;hotspot_tooltip_position&quot;:&quot;yes&quot;,&quot;hotspot_position&quot;:&quot;left&quot;,&quot;hotspot_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;_id&quot;:&quot;c3599f5&quot;,&quot;index&quot;:4,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position_tablet&quot;:&quot;&quot;,&quot;hotspot_position_mobile&quot;:&quot;&quot;,&quot;hotspot_icon_position&quot;:null,&quot;hotspot_offset_x_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_x_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_text_wrap&quot;:&quot;&quot;}],&quot;tooltip_trigger&quot;:&quot;mouseenter&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;tooltip_position&quot;:&quot;top&quot;,&quot;tooltip_animation&quot;:&quot;e-hotspot--fade-in-out&quot;}\" data-widget_type=\"hotspot.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1852\" height=\"1209\" src=\"https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/08\/Pfeiffer-Vacuum-Hot-Spot.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-39890\" alt=\"Pfeiffer Vacuum\" srcset=\"https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/08\/Pfeiffer-Vacuum-Hot-Spot.png 1852w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/08\/Pfeiffer-Vacuum-Hot-Spot-300x196.png 300w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/08\/Pfeiffer-Vacuum-Hot-Spot-1024x668.png 1024w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/08\/Pfeiffer-Vacuum-Hot-Spot-768x501.png 768w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/08\/Pfeiffer-Vacuum-Hot-Spot-1536x1003.png 1536w\" sizes=\"(max-width: 1852px) 100vw, 1852px\" \/>\n\t\t\t\t\t\t<div class=\"e-hotspot elementor-repeater-item-1d59cc6  e-hotspot--position-right e-hotspot--position-top   e-hotspot--icon\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 61 61\"><g id=\"Gruppe_2715\" data-name=\"Gruppe 2715\"><g id=\"Ellipse_71\" data-name=\"Ellipse 71\"><circle cx=\"30.5\" cy=\"30.5\" r=\"30\" fill=\"none\" stroke-width=\"0\"><\/circle><path d=\"M30.5,60.5C13.958,60.5.5,47.042.5,30.5S13.958.5,30.5.5s30,13.458,30,30-13.458,30-30,30ZM30.5,1.5C14.509,1.5,1.5,14.509,1.5,30.5s13.009,29,29,29,29-13.009,29-29S46.491,1.5,30.5,1.5Z\" fill=\"#18365d\" stroke-width=\"0\"><\/path><\/g><g id=\"Ellipse_72\" data-name=\"Ellipse 72\"><circle cx=\"30.5\" cy=\"30.5\" r=\"5\" fill=\"#18365d\" stroke-width=\"0\"><\/circle><\/g><\/g><\/svg><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip  e-hotspot--tooltip-position e-hotspot--fade-in-out \" >\n\t\t\t\t\t\t<p><strong>Haute sensibilit\u00e9 de d\u00e9tection<\/strong>: <br \/>Spectrom\u00e8tre chauff\u00e9 pour l'analyse <br \/>des gaz de d\u00e9composition lib\u00e9r\u00e9s.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\n\t\n\t\t\t\t\t\t<div class=\"e-hotspot elementor-repeater-item-d909940  e-hotspot--position-right e-hotspot--position-top   e-hotspot--icon\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 61 61\"><g id=\"Gruppe_2715\" data-name=\"Gruppe 2715\"><g id=\"Ellipse_71\" data-name=\"Ellipse 71\"><circle cx=\"30.5\" cy=\"30.5\" r=\"30\" fill=\"none\" stroke-width=\"0\"><\/circle><path d=\"M30.5,60.5C13.958,60.5.5,47.042.5,30.5S13.958.5,30.5.5s30,13.458,30,30-13.458,30-30,30ZM30.5,1.5C14.509,1.5,1.5,14.509,1.5,30.5s13.009,29,29,29,29-13.009,29-29S46.491,1.5,30.5,1.5Z\" fill=\"#18365d\" stroke-width=\"0\"><\/path><\/g><g id=\"Ellipse_72\" data-name=\"Ellipse 72\"><circle cx=\"30.5\" cy=\"30.5\" r=\"5\" fill=\"#18365d\" stroke-width=\"0\"><\/circle><\/g><\/g><\/svg><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip  e-hotspot--tooltip-position e-hotspot--fade-in-out \" >\n\t\t\t\t\t\t<p><b>Compatibilit\u00e9 :<\/b><\/p>\n<p>Couplage facile avec les thermobalances (TG),<\/p>\n<p>Analyse thermique simultan\u00e9e (STA) et autres appareils thermoanalytiques.<\/p>\n<p>G\u00e9om\u00e9trie flexible pour une adaptation optimale \u00e0 l'espace de laboratoire disponible.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\n\t\n\t\t\t\t\t\t<div class=\"e-hotspot elementor-repeater-item-a507cce  e-hotspot--position-right e-hotspot--position-top   e-hotspot--icon\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 61 61\"><g id=\"Gruppe_2715\" data-name=\"Gruppe 2715\"><g id=\"Ellipse_71\" data-name=\"Ellipse 71\"><circle cx=\"30.5\" cy=\"30.5\" r=\"30\" fill=\"none\" stroke-width=\"0\"><\/circle><path d=\"M30.5,60.5C13.958,60.5.5,47.042.5,30.5S13.958.5,30.5.5s30,13.458,30,30-13.458,30-30,30ZM30.5,1.5C14.509,1.5,1.5,14.509,1.5,30.5s13.009,29,29,29,29-13.009,29-29S46.491,1.5,30.5,1.5Z\" fill=\"#18365d\" stroke-width=\"0\"><\/path><\/g><g id=\"Ellipse_72\" data-name=\"Ellipse 72\"><circle cx=\"30.5\" cy=\"30.5\" r=\"5\" fill=\"#18365d\" stroke-width=\"0\"><\/circle><\/g><\/g><\/svg><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip  e-hotspot--tooltip-position e-hotspot--fade-in-out \" >\n\t\t\t\t\t\t<p><strong>Trois zones de chauffage s\u00e9par\u00e9es :<\/strong> <br \/>Assurer un minimum d'effets de dilution <br \/>et <br \/>des r\u00e9sultats pr\u00e9cis.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\n\t\n\t\t\t\t\t\t<div class=\"e-hotspot elementor-repeater-item-24ed251  e-hotspot--position-right e-hotspot--position-top   e-hotspot--icon\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 61 61\"><g id=\"Gruppe_2715\" data-name=\"Gruppe 2715\"><g id=\"Ellipse_71\" data-name=\"Ellipse 71\"><circle cx=\"30.5\" cy=\"30.5\" r=\"30\" fill=\"none\" stroke-width=\"0\"><\/circle><path d=\"M30.5,60.5C13.958,60.5.5,47.042.5,30.5S13.958.5,30.5.5s30,13.458,30,30-13.458,30-30,30ZM30.5,1.5C14.509,1.5,1.5,14.509,1.5,30.5s13.009,29,29,29,29-13.009,29-29S46.491,1.5,30.5,1.5Z\" fill=\"#18365d\" stroke-width=\"0\"><\/path><\/g><g id=\"Ellipse_72\" data-name=\"Ellipse 72\"><circle cx=\"30.5\" cy=\"30.5\" r=\"5\" fill=\"#18365d\" stroke-width=\"0\"><\/circle><\/g><\/g><\/svg><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip  e-hotspot--tooltip-position e-hotspot--fade-in-out \" >\n\t\t\t\t\t\t<p><b>Applications multiples :<\/b><\/p>\n<p>Spectroscopie de masse en ligne \u00e0 haute r\u00e9solution en phase gazeuse jusqu'\u00e0 300 AMU<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\n\t\n\t\t\t\t\t\t<div class=\"e-hotspot elementor-repeater-item-c3599f5  e-hotspot--position-right e-hotspot--position-top   e-hotspot--icon\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 61 61\"><g id=\"Gruppe_2715\" data-name=\"Gruppe 2715\"><g id=\"Ellipse_71\" data-name=\"Ellipse 71\"><circle cx=\"30.5\" cy=\"30.5\" r=\"30\" fill=\"none\" stroke-width=\"0\"><\/circle><path d=\"M30.5,60.5C13.958,60.5.5,47.042.5,30.5S13.958.5,30.5.5s30,13.458,30,30-13.458,30-30,30ZM30.5,1.5C14.509,1.5,1.5,14.509,1.5,30.5s13.009,29,29,29,29-13.009,29-29S46.491,1.5,30.5,1.5Z\" fill=\"#18365d\" stroke-width=\"0\"><\/path><\/g><g id=\"Ellipse_72\" data-name=\"Ellipse 72\"><circle cx=\"30.5\" cy=\"30.5\" r=\"5\" fill=\"#18365d\" stroke-width=\"0\"><\/circle><\/g><\/g><\/svg><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip  e-hotspot--tooltip-position e-hotspot--fade-in-out \" >\n\t\t\t\t\t\t<p><strong>Conception robuste<\/strong>: <br \/>Syst\u00e8me \u00e9tanche au vide <br \/>pour des mesures fiables et <br \/>r\u00e9p\u00e9tables.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\n\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0e8fa53 e-flex e-con-boxed e-con e-parent\" data-id=\"0e8fa53\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ca91505 e-con-full e-flex e-con e-child\" data-id=\"ca91505\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-761add6 elementor-widget elementor-widget-heading\" data-id=\"761add6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vous avez des questions ? N'h\u00e9sitez pas \u00e0 nous appeler ! <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f3641a elementor-widget elementor-widget-text-editor\" data-id=\"6f3641a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>+49 (0) 9287\/880 0<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85a5d33 elementor-widget elementor-widget-text-editor\" data-id=\"85a5d33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Notre service est disponible du lundi au<br \/> jeudi de 8h \u00e0 16h<br \/> et vendredi de 8h \u00e0 12h.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e2ac59 e-con-full e-flex e-con e-child\" data-id=\"6e2ac59\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c56b325 e-transform elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"c56b325\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:500,&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-5,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous sommes l\u00e0 pour vous !<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e5e798 e-flex e-con-boxed e-con e-parent\" data-id=\"5e5e798\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5be8efb e-con-full e-flex e-con e-child\" data-id=\"5be8efb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bc786ef elementor-widget elementor-widget-menu-anchor\" data-id=\"bc786ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"specifications\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad1d555 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ad1d555\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:250}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L40 EGA QMS - Sp\u00e9cifications<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-22f2227 e-flex e-con-boxed e-con e-parent\" data-id=\"22f2227\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c69953 elementor-invisible elementor-widget elementor-widget-shortcode\" data-id=\"2c69953\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<table id=\"tablepress-191\" class=\"tablepress tablepress-id-191\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\"><h3><strong>MODEL PFEIFFER THERMOSTAR<\/strong><\/h3><\/th><th class=\"column-2\"><h3><strong>EGA - QMS (L40 EGA QMS\/EGA COUPLING \/ GAS ANALYSIS)<\/strong><\/h3><\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Mass range:<\/td><td class=\"column-2\">100\/200\/300 AMU<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Detector:<\/td><td class=\"column-2\">Faraday and SEV (Channeltron)<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Ion source:<\/td><td class=\"column-2\">Electron impact, energy 100 eV<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Vacuum system:<\/td><td class=\"column-2\">Turbomolecular pump and diaphragm pump (oil-free vacuum)<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Heating:<\/td><td class=\"column-2\">Adapter head, capillary and QMS<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">Coupling with:<\/td><td class=\"column-2\">DSC, TGA, STA via heatable adapter accessories<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-191 from cache --><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-79e2514 e-flex e-con-boxed e-con e-parent\" data-id=\"79e2514\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-aa6b4e9 e-con-full e-flex e-con e-child\" data-id=\"aa6b4e9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8c46d5d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"8c46d5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:250}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Accessoires disponibles<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19c06e7 elementor-widget elementor-widget-text-editor\" data-id=\"19c06e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Analyse du pouls<\/strong><\/h3><p>L&rsquo;analyse par impulsions consiste \u00e0 injecter une quantit\u00e9 pr\u00e9cise de liquide ou de gaz dans la thermobalance (TGA) ou l&rsquo;analyseur thermique simultan\u00e9 (STA). Cela \u00e9largit consid\u00e9rablement les possibilit\u00e9s de mesure : le MS ou le FTIR peut d\u00e9sormais \u00eatre \u00e9talonn\u00e9. Les d\u00e9gagements gazeux peuvent \u00eatre quantifi\u00e9s avec pr\u00e9cision gr\u00e2ce \u00e0 cette m\u00e9thode.<\/p><h3><strong>MS-Sniffer<\/strong><\/h3><p>En raison de la pression d&rsquo;entr\u00e9e limit\u00e9e du MS, le gaz d&rsquo;\u00e9chantillonnage doit \u00eatre pr\u00e9lev\u00e9 apr\u00e8s un r\u00e9gulateur de pression (\u00e0 la pression ambiante). Par cons\u00e9quent, seules les substances qui peuvent passer par le pi\u00e8ge de refroidissement peuvent \u00eatre analys\u00e9es.<\/p><p>Les d\u00e9gagements gazeux des \u00e9chantillons sont dirig\u00e9s directement vers l&rsquo;analyseur QMS via un tr\u00e8s petit orifice. Cette petite ouverture (ou buse) r\u00e9duit la pression dans le r\u00e9cipient sous pression \u00e0 la pression d&rsquo;entr\u00e9e autoris\u00e9e pour le QMS. Comme cet orifice se trouve dans la zone chaude du four, il ne peut pas y avoir de condensation des d\u00e9gagements gazeux. Comme il y a un vide d&rsquo;environ <sup> 1e-5<\/sup> mbar entre l&rsquo;ouverture et la source d&rsquo;ions du QMS, toute condensation est \u00e9galement exclue \u00e0 cet endroit.<\/p><p>Le renifleur est plac\u00e9 directement au-dessus de l&rsquo;\u00e9chantillon. Cela est possible gr\u00e2ce au mat\u00e9riau du renifleur, qui peut r\u00e9sister aux temp\u00e9ratures de la zone chaude du four.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-88fc44b e-con-full e-flex e-con e-child\" data-id=\"88fc44b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-da0bac6 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"da0bac6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" class=\"alignnone wp-image-19630 size-full\" src=\"https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/QMS_Mass_Spectrometer_MS_Sniffer-1024x711-1.jpg\" alt=\"\" width=\"1024\" height=\"711\" srcset=\"https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/QMS_Mass_Spectrometer_MS_Sniffer-1024x711-1.jpg 1024w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/QMS_Mass_Spectrometer_MS_Sniffer-1024x711-1-300x208.jpg 300w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/QMS_Mass_Spectrometer_MS_Sniffer-1024x711-1-768x533.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-19608 size-large\" src=\"https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/MASB-Gas-Vapor-Diagram-1024x526.png\" alt=\"\" width=\"1024\" height=\"526\" srcset=\"https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/MASB-Gas-Vapor-Diagram-1024x526.png 1024w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/MASB-Gas-Vapor-Diagram-300x154.png 300w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/MASB-Gas-Vapor-Diagram-768x395.png 768w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/MASB-Gas-Vapor-Diagram-1536x789.png 1536w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/MASB-Gas-Vapor-Diagram-2048x1052.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-598c511 e-flex e-con-boxed e-con e-parent\" data-id=\"598c511\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4ba3f7f e-con-full e-flex e-con e-child\" data-id=\"4ba3f7f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b79e5f4 elementor-widget elementor-widget-menu-anchor\" data-id=\"b79e5f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"applications\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01430c2 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"01430c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:250}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Votre industrie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-884e0d8 e-con-full e-flex e-con e-child\" data-id=\"884e0d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a22e36b e-flex e-con-boxed e-con e-parent\" data-id=\"a22e36b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-697f894 e-con-full e-flex e-con e-child\" data-id=\"697f894\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8effb88 elementor-widget elementor-widget-text-editor\" data-id=\"8effb88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Exemple d&rsquo;application : ciment<\/strong><\/p><p>La combinaison de l&rsquo;analyse thermique et de la spectroscopie de masse est une m\u00e9thode tr\u00e8s puissante pour identifier et quantifier les composants de la mati\u00e8re premi\u00e8re et \u00e9galement un outil pour simuler le processus de fabrication des mat\u00e9riaux de construction. Les composants du mat\u00e9riau brut du ciment sont : M\u00e9lange de composants c\u00e9ramiques (gypse, carbonate de calcium, etc.) ainsi que de composants organiques.<\/p><p><strong>Analyse avec STA et QMS<\/strong><\/p><p>L&rsquo;image montre la <a href=\"https:\/\/www.linseis.com\/fr\/produits\/tga-thermogravimetry\/\">thermogravim\u00e9trie simultan\u00e9e (TGA)<\/a> combin\u00e9e \u00e0 la calorim\u00e9trie diff\u00e9rentielle \u00e0 balayage (DSC) et \u00e0 la spectroscopie de masse (MS). La spectrom\u00e9trie de masse permet d&rsquo;identifier les gaz d\u00e9velopp\u00e9s \u00e0 partir du mat\u00e9riau. La spectrom\u00e9trie de masse montre des pics de H<sub>2<\/sub>O \u00e0 basse temp\u00e9rature, tr\u00e8s probablement du gypse. Les pics DSC et le signal du spectrom\u00e8tre de masse entre ~ 300 \u00b0C &#8211; 400 \u00b0C indiquent la d\u00e9composition des composants organiques. Lepic de CO<sub>2<\/sub> \u00e0 ~ 800 \u00b0C indique la d\u00e9composition de CaCO<sub>3<\/sub>. A ~ 1300 \u00b0C, le CaSO<sub>4<\/sub> se d\u00e9compose (pic de SO<sub>2<\/sub> ).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f9f495 e-con-full e-flex e-con e-child\" data-id=\"4f9f495\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a501a14 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"a501a14\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"501\" src=\"https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/App_STA_QMS_Cement_Raw_Material-1024x641.png\" class=\"attachment-large size-large wp-image-19686\" alt=\"\" srcset=\"https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/App_STA_QMS_Cement_Raw_Material-1024x641.png 1024w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/App_STA_QMS_Cement_Raw_Material-300x188.png 300w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/App_STA_QMS_Cement_Raw_Material-768x481.png 768w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/App_STA_QMS_Cement_Raw_Material-1536x962.png 1536w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/App_STA_QMS_Cement_Raw_Material-2048x1282.png 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0dd5157 e-flex e-con-boxed e-con e-parent\" data-id=\"0dd5157\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7d4a119 e-con-full e-flex e-con e-child\" data-id=\"7d4a119\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-abfd77b elementor-invisible elementor-widget elementor-widget-image\" data-id=\"abfd77b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"488\" src=\"https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/STA-PT-1600-Decomposition-of-CaC2O4-.-H2O-1024x625.png\" class=\"attachment-large size-large wp-image-19717\" alt=\"\" srcset=\"https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/STA-PT-1600-Decomposition-of-CaC2O4-.-H2O-1024x625.png 1024w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/STA-PT-1600-Decomposition-of-CaC2O4-.-H2O-300x183.png 300w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/STA-PT-1600-Decomposition-of-CaC2O4-.-H2O-768x469.png 768w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/STA-PT-1600-Decomposition-of-CaC2O4-.-H2O-1536x938.png 1536w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/STA-PT-1600-Decomposition-of-CaC2O4-.-H2O.png 1553w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c37be1 e-con-full e-flex e-con e-child\" data-id=\"2c37be1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a7b1e5 elementor-widget elementor-widget-text-editor\" data-id=\"5a7b1e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>Exemple d&rsquo;application : d\u00e9composition de CaC<sub>2<sub>O<sub>4<\/sub><\/strong>\n\nLes gaz produits par la d\u00e9composition de l&rsquo;oxalate de calcium ont \u00e9t\u00e9 introduits dans le spectrom\u00e8tre de masse \u00e0 l&rsquo;aide d&rsquo;un capillaire chauff\u00e9. Les courants ioniques pour les nombres de masse 18 (eau), 28 (monoxyde de carbone) et 44 (dioxyde de carbone) ont \u00e9t\u00e9 import\u00e9s dans le diagramme.\n\nLa courbe TG rouge montre trois \u00e9tapes significatives de perte de masse, qui sont \u00e9galement visibles sur la courbe DSC bleue en tant qu&rsquo;\u00e9v\u00e9nements endothermiques. La premi\u00e8re, \u00e0 environ 150 \u00b0C, est la perte d&rsquo;eau de cristallisation, visible dans le spectrom\u00e8tre de masse comme une augmentation de l&rsquo;intensit\u00e9 de la trace 18 du courant ionique. Le deuxi\u00e8me effet, \u00e0 450 \u00b0C, montre la perte d&rsquo;une mol\u00e9cule de CO, qui est surveill\u00e9e par la trace de courant ionique 28. Enfin, le troisi\u00e8me effet, \u00e0 environ 750 \u00b0C, montre la perte de <sub>CO2<\/sub>, visible sous forme de pic dans le courant ionique 44.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d62e1ad e-flex e-con-boxed e-con e-parent\" data-id=\"d62e1ad\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-14b0177 e-con-full e-flex e-con e-child\" data-id=\"14b0177\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca3163d elementor-widget elementor-widget-menu-anchor\" data-id=\"ca3163d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"downloads\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28c8c55 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"28c8c55\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bien inform\u00e9<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9f0f5c elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"d9f0f5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">T\u00e9l\u00e9chargements<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0266e4 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"d0266e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Tout en un clin d'\u0153il<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b3a469e e-con-full e-flex e-con e-child\" data-id=\"b3a469e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a4d4d2e e-flex e-con-boxed e-con e-parent\" data-id=\"a4d4d2e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aa3cea9 elementor-widget elementor-widget-n-carousel\" data-id=\"aa3cea9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;bb638bb&quot;},{&quot;_id&quot;:&quot;7040d27&quot;,&quot;slide_title&quot;:&quot;Slide #4&quot;}],&quot;slides_to_show&quot;:&quot;4&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;slides_to_show_tablet&quot;:&quot;3&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 2\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9bcb78 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"c9bcb78\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e16567 elementor-widget elementor-widget-image\" data-id=\"5e16567\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/Linseis-Couplings-Gas-Analysis-EGA-FTIR_Seite_01-724x1024.jpg\" class=\"attachment-large size-large wp-image-19367\" alt=\"\" srcset=\"https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/Linseis-Couplings-Gas-Analysis-EGA-FTIR_Seite_01-724x1024.jpg 724w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/Linseis-Couplings-Gas-Analysis-EGA-FTIR_Seite_01-212x300.jpg 212w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/Linseis-Couplings-Gas-Analysis-EGA-FTIR_Seite_01-768x1086.jpg 768w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/Linseis-Couplings-Gas-Analysis-EGA-FTIR_Seite_01-1086x1536.jpg 1086w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/Linseis-Couplings-Gas-Analysis-EGA-FTIR_Seite_01-1448x2048.jpg 1448w, https:\/\/www.linseis.com\/wp-content\/uploads\/2024\/07\/Linseis-Couplings-Gas-Analysis-EGA-FTIR_Seite_01-scaled.jpg 1810w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f10df1 elementor-widget elementor-widget-heading\" data-id=\"1f10df1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><b>Couplings \/ Analyses de gaz\nBrochure produit (PDF)<\/b><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4334c60 elementor-widget elementor-widget-button\" data-id=\"4334c60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/wp-content\/uploads\/2024\/07\/Linseis-Couplings-Gas-Analysis-EGA-FTIR.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 11 16\"><rect id=\"Rechteck_1599\" data-name=\"Rechteck 1599\" x=\".129\" y=\"14.489\" width=\"10.742\" height=\"1.33\" fill=\"#0870b8\" stroke-width=\"0\"><\/rect><path id=\"Pfad_2872\" data-name=\"Pfad 2872\" d=\"M4.841.181v10.033l-3.2-3.2-.941.94,4.8,4.8,4.8-4.8-.941-.94-3.2,3.2V.181h-1.318Z\" fill=\"#0870b8\" stroke-width=\"0\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">t\u00e9l\u00e9charger<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 2\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48d4b44 e-flex e-con-boxed e-con e-child\" data-id=\"48d4b44\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8f60226 e-flex e-con-boxed e-con e-parent\" data-id=\"8f60226\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e9bcac0 elementor-widget elementor-widget-html\" data-id=\"e9bcac0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script type=\"application\/ld+json\">\r\n{\r\n  \"@context\": \"https:\/\/schema.org\",\r\n  \"@type\": \"FAQPage\",\r\n  \"mainEntity\": [{\r\n    \"@type\": \"Question\",\r\n    \"name\": \"Qu\u2019est-ce que la spectrom\u00e9trie de masse (MS)\",\r\n    \"acceptedAnswer\": {\r\n      \"@type\": \"Answer\",\r\n      \"text\": \"La spectrom\u00e9trie de masse (MS) est une technique analytique permettant de mesurer la masse d\u2019atomes ou de mol\u00e9cules.\"\r\n    }\r\n  },{\r\n    \"@type\": \"Question\",\r\n    \"name\": \"Comment fonctionne la spectrom\u00e9trie de masse ?\",\r\n    \"acceptedAnswer\": {\r\n      \"@type\": \"Answer\",\r\n      \"text\": \"La spectrom\u00e9trie de masse fonctionne en ionisant les compos\u00e9s chimiques pour cr\u00e9er des mol\u00e9cules ou des fragments de mol\u00e9cules charg\u00e9s et en mesurant leur rapport masse\/charge en pla\u00e7ant les mol\u00e9cules charg\u00e9es dans un champ magn\u00e9tique (quadrip\u00f4le) et en surveillant leur interaction.\"\r\n    }\r\n  },{\r\n    \"@type\": \"Question\",\r\n    \"name\": \"Qu\u2019est-ce que le QMS (spectrom\u00e8tre de masse quadripolaire) ?\",\r\n    \"acceptedAnswer\": {\r\n      \"@type\": \"Answer\",\r\n      \"text\": \"Le QMS \u2013 couplage de spectrom\u00e8tre de masse quadripolaire est un spectrom\u00e8tre de masse de pointe avec un syst\u00e8me d\u2019entr\u00e9e chauff\u00e9. Le QMS est utilis\u00e9 pour l\u2019analyse de la d\u00e9composition volatile. Tous les appareils Linseis offrent une solution logicielle int\u00e9gr\u00e9e qui permet d\u2019\u00e9valuer simultan\u00e9ment l\u2019analyse thermique et la technique EGA.\"\r\n    }\r\n  },{\r\n    \"@type\": \"Question\",\r\n    \"name\": \"Quels sont les avantages du couplage d\u2019une thermobalance Linseis avec un spectrom\u00e8tre de masse ?\",\r\n    \"acceptedAnswer\": {\r\n      \"@type\": \"Answer\",\r\n      \"text\": \"Le couplage de la thermobalance Linseis avec un spectrom\u00e8tre de masse permet d\u2019obtenir un r\u00e9sultat tr\u00e8s fiable. EGA (analyse des gaz d\u2019\u00e9mission).\r\n\r\nCela peut fournir des informations tr\u00e8s int\u00e9ressantes pour la caract\u00e9risation des mat\u00e9riaux lors du d\u00e9veloppement de nouvelles c\u00e9ramiques, de produits pharmaceutiques ou de polym\u00e8res et de m\u00e9taux. Il est \u00e9galement possible d\u2019effectuer des \u00e9tudes sur l\u2019impact environnemental des produits qui d\u00e9gagent des gaz, par exemple lors de la gestion des d\u00e9chets\/de l\u2019incin\u00e9ration ou dans les ateliers de peinture automobile.\"\r\n    }\r\n  }]\r\n}\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":0,"parent":41434,"menu_order":0,"template":"","categories":[263,260],"class_list":["post-41640","messgeraete","type-messgeraete","status-publish","hentry","category-analyse-thermique","category-ega-gasanalyse-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.linseis.com\/fr\/wp-json\/wp\/v2\/messgeraete\/41640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.linseis.com\/fr\/wp-json\/wp\/v2\/messgeraete"}],"about":[{"href":"https:\/\/www.linseis.com\/fr\/wp-json\/wp\/v2\/types\/messgeraete"}],"version-history":[{"count":0,"href":"https:\/\/www.linseis.com\/fr\/wp-json\/wp\/v2\/messgeraete\/41640\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.linseis.com\/fr\/wp-json\/wp\/v2\/messgeraete\/41434"}],"wp:attachment":[{"href":"https:\/\/www.linseis.com\/fr\/wp-json\/wp\/v2\/media?parent=41640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.linseis.com\/fr\/wp-json\/wp\/v2\/categories?post=41640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}